{"id":8644,"date":"2022-06-15T15:09:14","date_gmt":"2022-06-15T13:09:14","guid":{"rendered":"https:\/\/www.leaplytics.de\/?page_id=8644"},"modified":"2025-10-14T22:41:42","modified_gmt":"2025-10-14T20:41:42","slug":"zkusebni-verze","status":"publish","type":"page","link":"https:\/\/www.leaplytics.de\/cs\/zkusebni-verze\/","title":{"rendered":"\u017d\u00e1dost o zkou\u0161ku"},"content":{"rendered":"<p>Chcete zku\u0161ebn\u00ed dobu? Vypl\u0148te pros\u00edm kontaktn\u00ed formul\u00e1\u0159. R\u00e1di v\u00e1m e-mailem za\u0161leme \u010dty\u0159t\u00fddenn\u00ed zku\u0161ebn\u00ed licenci.<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-52fff7ef-9cf3-4f0c-a56f-a21c84af0066\" id=\"wpforms-10637\"><form id=\"wpforms-form-10637\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"10637\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/cs\/wp-json\/wp\/v2\/pages\/8644\" data-token=\"c3f15d22a1b0edbc4a04e3283e70f551\" data-token-time=\"1788309883\" data-trp-original-action=\"\/cs\/wp-json\/wp\/v2\/pages\/8644\"><noscript class=\"wpforms-error-noscript\">Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v prohl\u00ed\u017ee\u010di JavaScript.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-10637-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">N\u00e1zev <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-10637-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-10637-field_0\" class=\"wpforms-field-sublabel after\">K\u0159estn\u00ed jm\u00e9no<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-10637-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-10637-field_0-last\" class=\"wpforms-field-sublabel after\">P\u0159\u00edjmen\u00ed<\/label><\/div><\/div><\/div><div id=\"wpforms-10637-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-10637-field_1\">E-mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-10637-field_1\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-restricted-email=\"1\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-10637-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-10637-field_3\">Spole\u010dnost <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10637-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-10637-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-10637-field_4\">Zvolte si pros\u00edm platformu BI: <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-10637-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required=\"required\"><option value=\"Power BI\" >Power BI<\/option><option value=\"Qlik Sense\" >Qlik Sense<\/option><\/select><\/div><div id=\"wpforms-10637-field_6-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"6\"><label class=\"wpforms-field-label\">Vyberte si pros\u00edm sv\u016fj vizu\u00e1l: <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-10637-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-10637-field_6_1\" name=\"wpforms[fields][6][]\" value=\"Risk Heatmap\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-10637-field_6_1\">Mapa rizik<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-10637-field_6_2\" name=\"wpforms[fields][6][]\" value=\"Traffic Light\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-10637-field_6_2\">Semafor<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-10637-field_6_3\" name=\"wpforms[fields][6][]\" value=\"Gantt Chart\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-10637-field_6_3\">Gantt\u016fv diagram<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-10637-field_6_5\" name=\"wpforms[fields][6][]\" value=\"Markdown Viewer\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-10637-field_6_5\">Prohl\u00ed\u017ee\u010d Markdown<\/label><\/li><\/ul><\/div><div id=\"wpforms-10637-field_7-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"7\"><label class=\"wpforms-field-label\">Dohoda o GDPR <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-10637-field_7\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-10637-field_7_1\" name=\"wpforms[fields][7][]\" value=\"I consent to having this website store my submitted information so they can respond to my inquiry.\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-10637-field_7_1\">Souhlas\u00edm s t\u00edm, aby tyto webov\u00e9 str\u00e1nky ukl\u00e1daly mnou zaslan\u00e9 informace a mohly tak odpov\u011bd\u011bt na m\u016fj dotaz.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"10637\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/pages\/8644\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-10637\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Odeslat<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.leaplytics.de\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Na\u010d\u00edt\u00e1n\u00ed\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"cs\"\/><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Chcete zku\u0161ebn\u00ed dobu? Vypl\u0148te pros\u00edm kontaktn\u00ed formul\u00e1\u0159. R\u00e1di v\u00e1m e-mailem za\u0161leme \u010dty\u0159t\u00fddenn\u00ed zku\u0161ebn\u00ed licenci.<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8644","page","type-page","status-publish","hentry","latest_post"],"_links":{"self":[{"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/pages\/8644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/comments?post=8644"}],"version-history":[{"count":2,"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/pages\/8644\/revisions"}],"predecessor-version":[{"id":14030,"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/pages\/8644\/revisions\/14030"}],"wp:attachment":[{"href":"https:\/\/www.leaplytics.de\/cs\/wp-json\/wp\/v2\/media?parent=8644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}